{"id":339120,"date":"2024-05-28T11:10:51","date_gmt":"2024-05-28T09:10:51","guid":{"rendered":"https:\/\/bico.ch\/?post_type=blog&#038;p=339120"},"modified":"2024-05-28T11:20:56","modified_gmt":"2024-05-28T09:20:56","slug":"donnees-des-technologies-portables-au-laboratoire-du-sommeil","status":"publish","type":"blog","link":"https:\/\/bico.ch\/fr\/blog-du-sommeil\/donnees-des-technologies-portables-au-laboratoire-du-sommeil\/","title":{"rendered":"\u00abLes donn\u00e9es des technologies portables pourraient remplacer les consultations au laboratoire du sommeil\u00bb"},"content":{"rendered":"\n<div id=\"lead-text-block_14b57136f22aa8e0671678ee2623ee84\" class=\"lead-text \n mt-medium mb-medium\">\n      <div class=\"container\">\n      <div class=\"row\">\n        <div class=\"offset-xl-2 col-xl-8\">\n\n          \n          \n          \n                      <div class=\"wysiwyg text text-center \">\n              <p>Si tu dors mal, tu n\u2019es pas un cas isol\u00e9. Dr Albrecht Vorster, chercheur en sommeil, explique que la proportion de la population souffrant de troubles du sommeil pourrait atteindre 30%. Et il est convaincu que les technologies portables (wearables) peuvent jouer un r\u00f4le cl\u00e9 dans leur diagnostic.<\/p>\n            <\/div>\n          \n        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n\n\n<div id=\"anker-leiste-block_0cd23ff8a16c5c283fad1169c452608f\" class=\"anker-leiste \n mt-medium variante-2\">\n\n      <div class=\"container\">\n      <div class=\"row justify-content-center\">\n\n                  <div class=\"col-xxl-10\">\n            <div class=\"row gx-xl-5\">\n                              <div class=\"col-md-6 col-xl-4 anchor-item-wrapper d-flex\">\n                  <a class=\"anchor-item text-500\" href=\"#titel-text-block_30dc271b0254c886e8a54c21d10bf8b6\">\n                    <span>1. Certaines personnes ont beaucoup de mal \u00e0 bien dormir.<\/span>\n                    <i class=\"fak fa-icon-anchorlink\"><\/i>\n                  <\/a>\n                <\/div>\n                              <div class=\"col-md-6 col-xl-4 anchor-item-wrapper d-flex\">\n                  <a class=\"anchor-item text-500\" href=\"#titel-text-block_d06980d15b172bf8d4cc4f6e2ae82a20\">\n                    <span>2. Les technologies portables peuvent \u00eatre une solution.<\/span>\n                    <i class=\"fak fa-icon-anchorlink\"><\/i>\n                  <\/a>\n                <\/div>\n                              <div class=\"col-md-6 col-xl-4 anchor-item-wrapper d-flex\">\n                  <a class=\"anchor-item text-500\" href=\"#titel-text-block_be35d94a27ab04791a50f2b689d03ff2\">\n                    <span>3. Le laboratoire du sommeil n\u2019est plus le seul \u00e0 proposer des innovations techniques.<\/span>\n                    <i class=\"fak fa-icon-anchorlink\"><\/i>\n                  <\/a>\n                <\/div>\n                              <div class=\"col-md-6 col-xl-4 anchor-item-wrapper d-flex\">\n                  <a class=\"anchor-item text-500\" href=\"#titel-text-block_a50affb93d6eae49c70df33449ef3d6b\">\n                    <span>4. Les m\u00e9decins pourraient avoir plus de temps pour \u00e9couter.<\/span>\n                    <i class=\"fak fa-icon-anchorlink\"><\/i>\n                  <\/a>\n                <\/div>\n                              <div class=\"col-md-6 col-xl-4 anchor-item-wrapper d-flex\">\n                  <a class=\"anchor-item text-500\" href=\"#titel-text-block_0b9830143190efb99c6ec9b7f00c5a3d\">\n                    <span>5. Il existe m\u00eame des produits de bien-\u00eatre pour bien dormir.<\/span>\n                    <i class=\"fak fa-icon-anchorlink\"><\/i>\n                  <\/a>\n                <\/div>\n                          <\/div>\n          <\/div>\n        \n\n      <\/div>\n    <\/div>\n  \n<\/div>\n\n\n<div id=\"titel-text-block_d8fc15bdbe8f3a8bd691127df85669b8\" class=\"titel-text \n mt-medium\">\n\n      <div class=\"container\">\n\n      <div class=\"row justify-content-center\">\n        <div class=\"col-md-8 col-xl-6\">\n                                                    <div class=\"wysiwyg text  \">\n              <p>Rares sont les gens aussi repos\u00e9s en interview, m\u00eame lorsque le sommeil est leur m\u00e9tier et l\u2019objet de leurs recherches scientifiques. \u00c0 moins que ce soit justement parce qu\u2019il sait toute l\u2019importance d\u2019un bon sommeil qu\u2019Albrecht Vorster est tellement en forme?<\/p>\n<p>Je m\u2019entretiens avec le directeur de la Swiss Sleep House Bern \u00e0 la clinique universitaire de l\u2019Inselspital de Berne. N\u00e9 en 1985 \u00e0 Cologne, Albrecht Vorster a \u00e9tudi\u00e9 la biologie et la philosophie et obtenu son doctorat \u00e0 l\u2019Universit\u00e9 de T\u00fcbingen. Il a publi\u00e9 des livres et remport\u00e9 plusieurs Science Slam.<\/p>\n<p>Notre heure d\u2019interview a \u00e9t\u00e9 extr\u00eamement instructive pour moi.<\/p>\n            <\/div>\n                            <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n\n\n<div id=\"titel-text-block_30dc271b0254c886e8a54c21d10bf8b6\" class=\"titel-text \n mt-medium\">\n\n      <div class=\"container\">\n\n      <div class=\"row justify-content-center\">\n        <div class=\"col-md-8 col-xl-6\">\n                      <h3 class=\"h2   \">\n              1. Certaines personnes ont beaucoup de mal \u00e0 bien dormir.            <\/h3>\n                                                    <div class=\"wysiwyg text  \">\n              <p>Albrecht Vorster explique que m\u00eame si on lui pose souvent la question de la qualit\u00e9 du sommeil, sa r\u00e9ponse aide rarement \u00e0 y voir tr\u00e8s clair. Lui-m\u00eame dort plut\u00f4t normalement, mais <a href=\"https:\/\/bico.ch\/fr\/etude-sur-le-sommeil\/\">un tiers des gens environ sont affect\u00e9s par des troubles du sommeil<\/a>. La plupart d\u2019entre eux souffrent d\u2019apn\u00e9e du sommeil, une maladie qui, en l\u2019absence de traitement, peut avoir de lourdes cons\u00e9quences comme <a href=\"https:\/\/bico.ch\/fr\/blog-du-sommeil\/pourquoi-hypertension-et-manque-de-sommeil-peuvent-etre-lies\/\">l\u2019hypertension<\/a> ou <a href=\"https:\/\/bico.ch\/fr\/blog-du-sommeil\/manque-de-sommeil-et-baisse-de-concentration-lien-entre-les-deux-et-solutions\/\">la d\u00e9pression<\/a>.<\/p>\n            <\/div>\n                            <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n\n\n<div id=\"titel-text-block_d06980d15b172bf8d4cc4f6e2ae82a20\" class=\"titel-text \n mt-medium\">\n\n      <div class=\"container\">\n\n      <div class=\"row justify-content-center\">\n        <div class=\"col-md-8 col-xl-6\">\n                      <h3 class=\"h2   \">\n              2. Les technologies portables peuvent \u00eatre une solution.            <\/h3>\n                                                    <div class=\"wysiwyg text  \">\n              <p>Aujourd\u2019hui, nos smartphones, mais aussi les technologies portables, comme les montres connect\u00e9es, collectent de nombreuses donn\u00e9es sur leur propri\u00e9taire. Albrecht Vorster estime que ces mesures des signes vitaux sont utiles, mais qu\u2019il existe un moyen encore plus efficace de d\u00e9celer une \u00e9ventuelle apn\u00e9e du sommeil: les questionnaires papier ou en ligne, qui incluent par exemple des questions sur l\u2019\u00e2ge, le poids et le sexe. Toutefois, les applications qui analysent les donn\u00e9es des smartphones en se servant de leurs capteurs peuvent \u00e9galement fournir des informations pertinentes. Elles enregistrent les ronflements ou les apn\u00e9es et ces donn\u00e9es sont compl\u00e9t\u00e9es par celles sur le pouls et le rythme cardiaque livr\u00e9es par la montre connect\u00e9e.<\/p>\n            <\/div>\n                            <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n\n\n<div id=\"titel-text-block_be35d94a27ab04791a50f2b689d03ff2\" class=\"titel-text \n mt-medium\">\n\n      <div class=\"container\">\n\n      <div class=\"row justify-content-center\">\n        <div class=\"col-md-8 col-xl-6\">\n                      <h3 class=\"h2   \">\n              3. Le laboratoire du sommeil n\u2019est plus le seul \u00e0 proposer des innovations techniques.            <\/h3>\n                                                    <div class=\"wysiwyg text  \">\n              <p>Outre les montres connect\u00e9es, aujourd\u2019hui tr\u00e8s courantes, et le smartphone sur la table de chevet, d\u2019autres appareils de diagnostic peuvent selon Albrecht Vorster collecter de pr\u00e9cieuses donn\u00e9es. Il s\u2019agit par exemple de bagues oxym\u00e8tres, qui mesurent la saturation en oxyg\u00e8ne, ou de capteurs install\u00e9s sous, voire dans les matelas. Des T-Shirts qui produisent un trac\u00e9 ECG lorsqu\u2019ils sont port\u00e9s existent eux aussi d\u2019ores et d\u00e9j\u00e0. Tous ces appareils connect\u00e9s permettent de surveiller le sommeil d\u2019un individu comme seul un laboratoire du sommeil aurait pu le faire il y a encore quelques ann\u00e9es. Le d\u00e9fi est d\u00e9sormais moins d\u2019agr\u00e9ger les donn\u00e9es que de les interpr\u00e9ter correctement, ce qui exige incontestablement une expertise m\u00e9dicale.<\/p>\n            <\/div>\n                            <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n\n\n<div id=\"produktempfehlungen-block_bc44f092e432088995cc2270ee68bf6a\" class=\"produktempfehlungen \n mt-medium mb-medium\">\n\n      <div class=\"container\">\n\n      \n      <div class=\"swiper produktempfehlungen-swiper\">\n        <div class=\"swiper-wrapper\">\n                                    <div class=\"swiper-slide\">\n                <div class=\"woocommerce \"><ul class=\"products columns-4\">\n<li class=\"product type-product post-53264 status-publish first instock product_cat-matelas-et-surmatelas has-post-thumbnail taxable shipping-taxable purchasable product-type-variable has-default-attributes\">\n\t<div class=\"tags-wrapper\">\n\t\t\n\t\t\t<\/div>\n\n\t<a href=\"https:\/\/bico.ch\/fr\/produit\/matelas-bodyfine\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail-wrapper\"><img decoding=\"async\" loading=\"lazy\" width=\"600\" height=\"400\" src=\"https:\/\/bico.ch\/wp-content\/uploads\/2022\/12\/01-bico-matratze-bodyfine-cut-600x400.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"BICO BodyFine Matratze\" \/><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/bico.ch\/wp-content\/uploads\/2024\/10\/03-bico-matratze-bodyfine-v2-aspect-ratio-448-340-1.webp\" alt=\"BICO Matratze Bodyfine auf Bettgestell mit Duvet\" class=\"img-fluid attachment-woocommerce_thumbnail-overlay\" \/><\/div><h2 class=\"woocommerce-loop-product__title\">BodyFine<\/h2>\n\n\t\t\t<div class=\"woocommerce-loop-product__lead\">\n\t\t\tLe top des matelas de d\u00e9tente: une sensation enveloppante comme un c\u00e2lin. \t\t<\/div>\n\t\n\n\t<div class=\"star-rating\" role=\"img\" aria-label=\"Note 5 sur 5\"><span style=\"width:100%\">Note <strong class=\"rating\">5<\/strong> sur 5<\/span><\/div>\n\t<div class=\"price-wrapper\">\n\t\t<span class=\"price\">\n\t\t\t\t\t\t\t\t\t\t\t\t\u00e0 partir de CHF 2&rsquo;590.00\t\t\t\t\t\t\t\t\t<\/span>\n\n\t<\/div>\n\n<\/a><span class=\"gtm4wp_productdata\" style=\"display:none; visibility:hidden;\" data-gtm4wp_product_data=\"{&quot;internal_id&quot;:53264,&quot;item_id&quot;:&quot;H1016&quot;,&quot;item_name&quot;:&quot;BodyFine&quot;,&quot;sku&quot;:&quot;H1016&quot;,&quot;price&quot;:2590,&quot;stocklevel&quot;:null,&quot;stockstatus&quot;:&quot;instock&quot;,&quot;google_business_vertical&quot;:&quot;retail&quot;,&quot;item_category&quot;:&quot;Matelas &amp; surmatelas&quot;,&quot;id&quot;:&quot;H1016&quot;,&quot;productlink&quot;:&quot;https:\\\/\\\/bico.ch\\\/fr\\\/produit\\\/matelas-bodyfine\\\/&quot;,&quot;item_list_name&quot;:&quot;Liste g\\u00e9n\\u00e9rale des produits&quot;,&quot;index&quot;:1,&quot;product_type&quot;:&quot;variable&quot;,&quot;item_brand&quot;:&quot;&quot;}\"><\/span><\/li><\/ul>\n<\/div>              <\/div>\n                                                <div class=\"swiper-slide\">\n                <div class=\"woocommerce \"><ul class=\"products columns-4\">\n<li class=\"product type-product post-50085 status-publish first instock product_cat-matelas-et-surmatelas product_tag-populaire has-post-thumbnail taxable shipping-taxable purchasable product-type-variable has-default-attributes\">\n\t<div class=\"tags-wrapper\">\n\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"tag-item default\">\n\t\t\t\t\tPOPULAIRE\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/div>\n\n\t<a href=\"https:\/\/bico.ch\/fr\/produit\/matelas-climafine\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail-wrapper\"><img decoding=\"async\" loading=\"lazy\" width=\"600\" height=\"400\" src=\"https:\/\/bico.ch\/wp-content\/uploads\/2022\/10\/01-bico-matratze-climafine-cut-2-600x400.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"BICO Matratze Climafine h1247 Aufbau Matratzenkern bietet in den verschiedenen Koerperzonen die bestmoegliche Stuetzung und Druckentlastung fuer einen gesunden Schlaf\" \/><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/bico.ch\/wp-content\/uploads\/2024\/10\/03-bico-matratze-climafine-h1247-aspect-ratio-448-340.webp\" alt=\"BICO Matratze Climafine h1247 auf Bettgestell mit Duvet\" class=\"img-fluid attachment-woocommerce_thumbnail-overlay\" \/><\/div><h2 class=\"woocommerce-loop-product__title\">ClimaFine<\/h2>\n\n\t\t\t<div class=\"woocommerce-loop-product__lead\">\n\t\t\tLe top des matelas climatis\u00e9s, excellent climat de lit et soutien du corps.\t\t<\/div>\n\t\n\n\t\n\t<div class=\"price-wrapper\">\n\t\t<span class=\"price\">\n\t\t\t\t\t\t\t\t\t\t\t\t\u00e0 partir de CHF 2&rsquo;590.00\t\t\t\t\t\t\t\t\t<\/span>\n\n\t<\/div>\n\n<\/a><span class=\"gtm4wp_productdata\" style=\"display:none; visibility:hidden;\" data-gtm4wp_product_data=\"{&quot;internal_id&quot;:50085,&quot;item_id&quot;:&quot;H1247&quot;,&quot;item_name&quot;:&quot;ClimaFine&quot;,&quot;sku&quot;:&quot;H1247&quot;,&quot;price&quot;:2590,&quot;stocklevel&quot;:null,&quot;stockstatus&quot;:&quot;instock&quot;,&quot;google_business_vertical&quot;:&quot;retail&quot;,&quot;item_category&quot;:&quot;Matelas &amp; surmatelas&quot;,&quot;id&quot;:&quot;H1247&quot;,&quot;productlink&quot;:&quot;https:\\\/\\\/bico.ch\\\/fr\\\/produit\\\/matelas-climafine\\\/&quot;,&quot;item_list_name&quot;:&quot;Liste g\\u00e9n\\u00e9rale des produits&quot;,&quot;index&quot;:1,&quot;product_type&quot;:&quot;variable&quot;,&quot;item_brand&quot;:&quot;&quot;}\"><\/span><\/li><\/ul>\n<\/div>              <\/div>\n                                                <div class=\"swiper-slide\">\n                <div class=\"woocommerce \"><ul class=\"products columns-4\">\n<li class=\"product type-product post-50230 status-publish first instock product_cat-matelas-et-surmatelas product_tag-best-seller has-post-thumbnail taxable shipping-taxable purchasable product-type-variable has-default-attributes\">\n\t<div class=\"tags-wrapper\">\n\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"tag-item default\">\n\t\t\t\t\tBEST SELLER\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/div>\n\n\t<a href=\"https:\/\/bico.ch\/fr\/produit\/matelas-climaluxe\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"thumbnail-wrapper\"><img decoding=\"async\" loading=\"lazy\" width=\"600\" height=\"400\" src=\"https:\/\/bico.ch\/wp-content\/uploads\/2022\/10\/01-bico-matratze-climaluxe-h1241-cut-1-600x400.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"BICO Matratze Climaluxe h1241 Matratze Aufbau\" \/><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/bico.ch\/wp-content\/uploads\/2024\/10\/03-bico-matratze-bodyfine-v2-aspect-ratio-448-340.webp\" alt=\"BICO Matratze Bodyfine auf Bettgestell mit Duvet\" class=\"img-fluid attachment-woocommerce_thumbnail-overlay\" \/><\/div><h2 class=\"woocommerce-loop-product__title\">ClimaLuxe<\/h2>\n\n\t\t\t<div class=\"woocommerce-loop-product__lead\">\n\t\t\tBest-seller des matelas BICO, comble tous les v\u0153ux en termes de climat et de ventilation. \t\t<\/div>\n\t\n\n\t<div class=\"star-rating\" role=\"img\" aria-label=\"Note 5 sur 5\"><span style=\"width:100%\">Note <strong class=\"rating\">5<\/strong> sur 5<\/span><\/div>\n\t<div class=\"price-wrapper\">\n\t\t<span class=\"price\">\n\t\t\t\t\t\t\t\t\t\t\t\t\u00e0 partir de CHF 2&rsquo;040.00\t\t\t\t\t\t\t\t\t<\/span>\n\n\t<\/div>\n\n<\/a><span class=\"gtm4wp_productdata\" style=\"display:none; visibility:hidden;\" data-gtm4wp_product_data=\"{&quot;internal_id&quot;:50230,&quot;item_id&quot;:&quot;H1241&quot;,&quot;item_name&quot;:&quot;ClimaLuxe&quot;,&quot;sku&quot;:&quot;H1241&quot;,&quot;price&quot;:2040,&quot;stocklevel&quot;:null,&quot;stockstatus&quot;:&quot;instock&quot;,&quot;google_business_vertical&quot;:&quot;retail&quot;,&quot;item_category&quot;:&quot;Matelas &amp; surmatelas&quot;,&quot;id&quot;:&quot;H1241&quot;,&quot;productlink&quot;:&quot;https:\\\/\\\/bico.ch\\\/fr\\\/produit\\\/matelas-climaluxe\\\/&quot;,&quot;item_list_name&quot;:&quot;Liste g\\u00e9n\\u00e9rale des produits&quot;,&quot;index&quot;:1,&quot;product_type&quot;:&quot;variable&quot;,&quot;item_brand&quot;:&quot;&quot;}\"><\/span><\/li><\/ul>\n<\/div>              <\/div>\n                              <\/div>\n        <div class=\"swiper-button-wrapper\">\n          <div class=\"swiper-button-prev\"><?xml version=\"1.0\"?>\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" class=\"icon icon_arrow_left-icon \" aria-labelledby=\"retour-icon\" role=\"img\">\n<g clip-path=\"url(#clip0_11139_13198)\">\n<path d=\"M11 18.9999L4 11.9999L11 4.99992\" stroke=\"#0F1531\"\/>\n<path d=\"M4 12L21.25 12\" stroke=\"#0F1531\"\/>\n<\/g>\n<defs>\n<clipPath id=\"clip0_11139_13198\">\n<rect width=\"24\" height=\"24\" rx=\"12\" transform=\"matrix(-1 0 0 1 24 0)\" fill=\"white\"\/>\n<\/clipPath>\n<\/defs>\n<title id=\"retour-icon\">Retour<\/title><\/svg>\n<\/div>\n          <div class=\"swiper-button-next\"><?xml version=\"1.0\"?>\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" class=\"icon icon_arrow_right-icon \" aria-labelledby=\"continuer-icon\" role=\"img\">\n<path d=\"M13 18.9999L20 11.9999L13 4.99992\" stroke=\"#0F1531\"\/>\n<path d=\"M20 12L2.75 12\" stroke=\"#0F1531\"\/>\n<title id=\"continuer-icon\">Continuer<\/title><\/svg>\n<\/div>\n        <\/div>\n      <\/div>\n\n    <\/div>\n  \n<\/div>\n\n\n<div id=\"titel-text-block_a50affb93d6eae49c70df33449ef3d6b\" class=\"titel-text \n mt-medium\">\n\n      <div class=\"container\">\n\n      <div class=\"row justify-content-center\">\n        <div class=\"col-md-8 col-xl-6\">\n                      <h3 class=\"h2   \">\n              4. Les m\u00e9decins pourraient avoir plus de temps pour \u00e9couter.            <\/h3>\n                                                    <div class=\"wysiwyg text  \">\n              <p>Malgr\u00e9 les progr\u00e8s technologiques, les laboratoires cliniques du sommeil restent indispensables pour traiter les troubles graves. Albrecht Vorster souligne n\u00e9anmoins que les technologies portables peuvent d\u00e9lester les m\u00e9decins au niveau du diagnostic et lib\u00e9rer ainsi du temps pour leur permettre d\u2019\u00eatre \u00e0 l\u2019\u00e9coute de la patient\u00e8le. Parce que c\u2019est lorsqu\u2019il r\u00e9fl\u00e9chit qu\u2019un m\u00e9decin est le plus pr\u00e9cieux. Mais pour cela, il a besoin de temps.<\/p>\n            <\/div>\n                            <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n\n\n<div id=\"titel-text-block_0b9830143190efb99c6ec9b7f00c5a3d\" class=\"titel-text \n mt-medium\">\n\n      <div class=\"container\">\n\n      <div class=\"row justify-content-center\">\n        <div class=\"col-md-8 col-xl-6\">\n                      <h3 class=\"h2   \">\n              5. Il existe m\u00eame des produits de bien-\u00eatre pour bien dormir.            <\/h3>\n                                                    <div class=\"wysiwyg text  \">\n              <p>Pour Albrecht Vorster, <a href=\"https:\/\/bico.ch\/fr\/blog-du-sommeil\/avec-ces-gadgets-de-sommeil-vous-demarrez-la-journee-du-bon-pied\/\">les gadgets<\/a> comme les r\u00e9veils lumineux ou les lampes \u00e0 lumi\u00e8re du jour sont un autre type de technique au service du sommeil. Ce ne sont pas des dispositifs m\u00e9dicaux, ni des appareils ayant une utilit\u00e9 m\u00e9dicale directe, mais ils peuvent eux aussi am\u00e9liorer la qualit\u00e9 du sommeil. Les lampes qui imitent la lumi\u00e8re naturelle facilitent par exemple l\u2019endormissement et le r\u00e9veil. Les personnes qui utilisent des lampes \u00e0 lumi\u00e8re du jour pour faire le plein de vitamine\u00a0D, notamment en hiver, devraient savoir que la plupart d\u2019entre elles ne sont pas adapt\u00e9es \u00e0 cet usage. Dans tous les cas, il faut s\u2019asseoir pr\u00e8s de la source lumineuse, qui doit \u00e9clairer en biais depuis le haut.<\/p>\n            <\/div>\n                            <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n\n\n<div id=\"titel-text-block_1bad0c227001b2f2151363d8511fbee0\" class=\"titel-text \n mt-medium\">\n\n      <div class=\"container\">\n\n      <div class=\"row justify-content-center\">\n        <div class=\"col-md-8 col-xl-6\">\n                                                    <div class=\"wysiwyg text  \">\n              <p>Remarque: cet article a \u00e9t\u00e9 publi\u00e9 sous forme d\u2019interview dans <a href=\"https:\/\/www.galaxus.ch\/fr\/page\/les-donnees-des-wearables-peuvent-remplacer-les-visites-au-laboratoire-du-sommeil-30687\" target=\"_blank\" rel=\"noopener\">le magazine Galaxus<\/a>. L\u2019auteur Martin Jungfer, Head of Content, y est responsable de l\u2019ensemble des articles r\u00e9dactionnels.<\/p>\n            <\/div>\n                            <\/div>\n      <\/div>\n    <\/div>\n  <\/div>","protected":false},"author":50,"comment_status":"open","ping_status":"closed","template":"","blog-taxonomies":[1020,1022],"class_list":["post-339120","blog","type-blog","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Donn\u00e9es des wearables au laboratoire du sommeil | BICO<\/title>\n<meta name=\"description\" content=\"Dr Albrecht Vorster, chercheur en sommeil, est convaincu que les technologies portables peuvent jouer un r\u00f4le cl\u00e9 dans le diagnostic.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bico.ch\/fr\/blog-du-sommeil\/donnees-des-technologies-portables-au-laboratoire-du-sommeil\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Donn\u00e9es des wearables au laboratoire du sommeil | BICO\" \/>\n<meta property=\"og:description\" content=\"Dr Albrecht Vorster, chercheur en sommeil, est convaincu que les technologies portables (wearables) peuvent jouer un r\u00f4le cl\u00e9 dans le diagnostic.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bico.ch\/fr\/blog-du-sommeil\/donnees-des-technologies-portables-au-laboratoire-du-sommeil\/\" \/>\n<meta property=\"og:site_name\" content=\"BICO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bicoswitzerland\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-28T09:20:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bico.ch\/wp-content\/uploads\/2024\/04\/blog-beitrag-wearables-bico.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"722\" \/>\n\t<meta property=\"og:image:height\" content=\"728\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bico.ch\\\/fr\\\/blog-du-sommeil\\\/donnees-des-technologies-portables-au-laboratoire-du-sommeil\\\/\",\"url\":\"https:\\\/\\\/bico.ch\\\/fr\\\/blog-du-sommeil\\\/donnees-des-technologies-portables-au-laboratoire-du-sommeil\\\/\",\"name\":\"Donn\u00e9es des wearables au laboratoire du sommeil | BICO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bico.ch\\\/fr\\\/#website\"},\"datePublished\":\"2024-05-28T09:10:51+00:00\",\"dateModified\":\"2024-05-28T09:20:56+00:00\",\"description\":\"Dr Albrecht Vorster, chercheur en sommeil, est convaincu que les technologies portables peuvent jouer un r\u00f4le cl\u00e9 dans le diagnostic.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bico.ch\\\/fr\\\/blog-du-sommeil\\\/donnees-des-technologies-portables-au-laboratoire-du-sommeil\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bico.ch\\\/fr\\\/blog-du-sommeil\\\/donnees-des-technologies-portables-au-laboratoire-du-sommeil\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bico.ch\\\/fr\\\/blog-du-sommeil\\\/donnees-des-technologies-portables-au-laboratoire-du-sommeil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/bico.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abLes donn\u00e9es des technologies portables pourraient remplacer les consultations au laboratoire du sommeil\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bico.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/bico.ch\\\/fr\\\/\",\"name\":\"BICO\",\"description\":\"F\u00fcr \u00e4 t\u00fc\u00fcf\u00e4 gsund\u00e4 Schlaaf.\u00ae\",\"publisher\":{\"@id\":\"https:\\\/\\\/bico.ch\\\/fr\\\/#organization\"},\"alternateName\":\"bico.ch\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bico.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bico.ch\\\/fr\\\/#organization\",\"name\":\"BICO\",\"url\":\"https:\\\/\\\/bico.ch\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/bico.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bico.ch\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/BICO_Logo_Black-e1667997604131.png\",\"contentUrl\":\"https:\\\/\\\/bico.ch\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/BICO_Logo_Black-e1667997604131.png\",\"width\":2481,\"height\":1754,\"caption\":\"BICO\"},\"image\":{\"@id\":\"https:\\\/\\\/bico.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/bicoswitzerland\",\"https:\\\/\\\/www.instagram.com\\\/bicoswitzerland\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCnyVAqYqj5XdkWKWY5CFJ3A\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/bicoswitzerland\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Donn\u00e9es des wearables au laboratoire du sommeil | BICO","description":"Dr Albrecht Vorster, chercheur en sommeil, est convaincu que les technologies portables peuvent jouer un r\u00f4le cl\u00e9 dans le diagnostic.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bico.ch\/fr\/blog-du-sommeil\/donnees-des-technologies-portables-au-laboratoire-du-sommeil\/","og_locale":"fr_FR","og_type":"article","og_title":"Donn\u00e9es des wearables au laboratoire du sommeil | BICO","og_description":"Dr Albrecht Vorster, chercheur en sommeil, est convaincu que les technologies portables (wearables) peuvent jouer un r\u00f4le cl\u00e9 dans le diagnostic.","og_url":"https:\/\/bico.ch\/fr\/blog-du-sommeil\/donnees-des-technologies-portables-au-laboratoire-du-sommeil\/","og_site_name":"BICO","article_publisher":"https:\/\/www.facebook.com\/bicoswitzerland","article_modified_time":"2024-05-28T09:20:56+00:00","og_image":[{"width":722,"height":728,"url":"https:\/\/bico.ch\/wp-content\/uploads\/2024\/04\/blog-beitrag-wearables-bico.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bico.ch\/fr\/blog-du-sommeil\/donnees-des-technologies-portables-au-laboratoire-du-sommeil\/","url":"https:\/\/bico.ch\/fr\/blog-du-sommeil\/donnees-des-technologies-portables-au-laboratoire-du-sommeil\/","name":"Donn\u00e9es des wearables au laboratoire du sommeil | BICO","isPartOf":{"@id":"https:\/\/bico.ch\/fr\/#website"},"datePublished":"2024-05-28T09:10:51+00:00","dateModified":"2024-05-28T09:20:56+00:00","description":"Dr Albrecht Vorster, chercheur en sommeil, est convaincu que les technologies portables peuvent jouer un r\u00f4le cl\u00e9 dans le diagnostic.","breadcrumb":{"@id":"https:\/\/bico.ch\/fr\/blog-du-sommeil\/donnees-des-technologies-portables-au-laboratoire-du-sommeil\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bico.ch\/fr\/blog-du-sommeil\/donnees-des-technologies-portables-au-laboratoire-du-sommeil\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bico.ch\/fr\/blog-du-sommeil\/donnees-des-technologies-portables-au-laboratoire-du-sommeil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/bico.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00abLes donn\u00e9es des technologies portables pourraient remplacer les consultations au laboratoire du sommeil\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/bico.ch\/fr\/#website","url":"https:\/\/bico.ch\/fr\/","name":"BICO","description":"F\u00fcr \u00e4 t\u00fc\u00fcf\u00e4 gsund\u00e4 Schlaaf.\u00ae","publisher":{"@id":"https:\/\/bico.ch\/fr\/#organization"},"alternateName":"bico.ch","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bico.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/bico.ch\/fr\/#organization","name":"BICO","url":"https:\/\/bico.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/bico.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/bico.ch\/wp-content\/uploads\/2022\/11\/BICO_Logo_Black-e1667997604131.png","contentUrl":"https:\/\/bico.ch\/wp-content\/uploads\/2022\/11\/BICO_Logo_Black-e1667997604131.png","width":2481,"height":1754,"caption":"BICO"},"image":{"@id":"https:\/\/bico.ch\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bicoswitzerland","https:\/\/www.instagram.com\/bicoswitzerland\/","https:\/\/www.youtube.com\/channel\/UCnyVAqYqj5XdkWKWY5CFJ3A","https:\/\/www.linkedin.com\/showcase\/bicoswitzerland\/"]}]}},"_links":{"self":[{"href":"https:\/\/bico.ch\/fr\/wp-json\/wp\/v2\/blog\/339120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bico.ch\/fr\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/bico.ch\/fr\/wp-json\/wp\/v2\/types\/blog"}],"author":[{"embeddable":true,"href":"https:\/\/bico.ch\/fr\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/bico.ch\/fr\/wp-json\/wp\/v2\/comments?post=339120"}],"version-history":[{"count":0,"href":"https:\/\/bico.ch\/fr\/wp-json\/wp\/v2\/blog\/339120\/revisions"}],"wp:attachment":[{"href":"https:\/\/bico.ch\/fr\/wp-json\/wp\/v2\/media?parent=339120"}],"wp:term":[{"taxonomy":"blog-taxonomies","embeddable":true,"href":"https:\/\/bico.ch\/fr\/wp-json\/wp\/v2\/blog-taxonomies?post=339120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}